{"id":394,"date":"2019-04-29T20:16:08","date_gmt":"2019-04-29T19:16:08","guid":{"rendered":"https:\/\/www.love-you.eu\/einkaufswagen\/"},"modified":"2019-04-29T20:16:08","modified_gmt":"2019-04-29T19:16:08","slug":"einkaufswagen","status":"publish","type":"page","link":"https:\/\/www.love-you.eu\/de\/einkaufswagen\/","title":{"rendered":"Einkaufswagen"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-394","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Einkaufswagen - #loveyouEU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.love-you.eu\/de\/einkaufswagen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einkaufswagen - #loveyouEU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.love-you.eu\/de\/einkaufswagen\/\" \/>\n<meta property=\"og:site_name\" content=\"#loveyouEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/embodyeurope\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@loveyou_eu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.love-you.eu\/de\/einkaufswagen\/\",\"url\":\"https:\/\/www.love-you.eu\/de\/einkaufswagen\/\",\"name\":\"Einkaufswagen - #loveyouEU\",\"isPartOf\":{\"@id\":\"https:\/\/www.love-you.eu\/de\/#website\"},\"datePublished\":\"2019-04-29T19:16:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.love-you.eu\/de\/einkaufswagen\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.love-you.eu\/de\/einkaufswagen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.love-you.eu\/de\/einkaufswagen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.love-you.eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einkaufswagen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.love-you.eu\/de\/#website\",\"url\":\"https:\/\/www.love-you.eu\/de\/\",\"name\":\"#loveyouEU\",\"description\":\"my future. my choice\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.love-you.eu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einkaufswagen - #loveyouEU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.love-you.eu\/de\/einkaufswagen\/","og_locale":"de_DE","og_type":"article","og_title":"Einkaufswagen - #loveyouEU","og_url":"https:\/\/www.love-you.eu\/de\/einkaufswagen\/","og_site_name":"#loveyouEU","article_publisher":"https:\/\/www.facebook.com\/embodyeurope\/","twitter_card":"summary_large_image","twitter_site":"@loveyou_eu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.love-you.eu\/de\/einkaufswagen\/","url":"https:\/\/www.love-you.eu\/de\/einkaufswagen\/","name":"Einkaufswagen - #loveyouEU","isPartOf":{"@id":"https:\/\/www.love-you.eu\/de\/#website"},"datePublished":"2019-04-29T19:16:08+00:00","breadcrumb":{"@id":"https:\/\/www.love-you.eu\/de\/einkaufswagen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.love-you.eu\/de\/einkaufswagen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.love-you.eu\/de\/einkaufswagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.love-you.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Einkaufswagen"}]},{"@type":"WebSite","@id":"https:\/\/www.love-you.eu\/de\/#website","url":"https:\/\/www.love-you.eu\/de\/","name":"#loveyouEU","description":"my future. my choice","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.love-you.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/www.love-you.eu\/de\/wp-json\/wp\/v2\/pages\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.love-you.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.love-you.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.love-you.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.love-you.eu\/de\/wp-json\/wp\/v2\/comments?post=394"}],"version-history":[{"count":0,"href":"https:\/\/www.love-you.eu\/de\/wp-json\/wp\/v2\/pages\/394\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.love-you.eu\/de\/wp-json\/wp\/v2\/media?parent=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}